{"id":3843,"date":"2026-06-03T17:58:28","date_gmt":"2026-06-03T20:58:28","guid":{"rendered":"https:\/\/feminismo.org.br\/ULFA\/?p=3843"},"modified":"2026-06-03T18:00:36","modified_gmt":"2026-06-03T21:00:36","slug":"amazonia-xiii-coloquio-universidade-em-dialogos-sustentaveis","status":"publish","type":"post","link":"https:\/\/feminismo.org.br\/ULFA\/amazonia-xiii-coloquio-universidade-em-dialogos-sustentaveis\/","title":{"rendered":"AMAZ\u00d4NIA: XIII COL\u00d3QUIO UNIVERSIDADE EM DI\u00c1LOGOS SUSTENT\u00c1VEIS"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dia Nacional da Educa\u00e7\u00e3o Ambiental &#8211; Universidade Federal do Par\u00e1 &#8211; Brasil<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Abertura da Programa\u00e7\u00e3o de Junho<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Neste Dia Nacional da Educa\u00e7\u00e3o Ambiental, o GEAM\/NAEA\/UFPA e a Turma do Curso de Especializa\u00e7\u00e3o em Educa\u00e7\u00e3o Ambiental e Projeto Pedag\u00f3gico na Gest\u00e3o de Escolas e de Sistemas de Meio Ambiente na Amaz\u00f4nia (PPLS\/NAEA\/UFPA) d\u00e3o in\u00edcio \u00e0 programa\u00e7\u00e3o da 13\u00aa edi\u00e7\u00e3o do Col\u00f3quio Universidade em Di\u00e1logos Sustent\u00e1veis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com o tema \u201cEduca\u00e7\u00e3o Ambiental na Gest\u00e3o da Vida Presente para Adiar o Fim do Mundo\u201d, o evento reunir\u00e1 educadores, gestores, pesquisadores e profissionais que atuam na constru\u00e7\u00e3o de pr\u00e1ticas sustent\u00e1veis na Amaz\u00f4nia paraense.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta \u00e9 a abertura de uma programa\u00e7\u00e3o que se desenvolver\u00e1 ao longo de todo o m\u00eas de junho, com diferentes atividades, di\u00e1logos e a\u00e7\u00f5es em diversos territ\u00f3rios, fortalecendo o compromisso com a Educa\u00e7\u00e3o Ambiental, a justi\u00e7a socioambiental e a sustentabilidade da vida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Painel:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Educa\u00e7\u00e3o Ambiental na Gest\u00e3o de Escolas e de Sistemas de Meio Ambiente na Amaz\u00f4nia<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">03 de junho de 2025 | 18h<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Audit\u00f3rio do Nucleo de Meio Ambiente\/NUMA\/UFPA<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Realiza\u00e7\u00e3o:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">GEAM\/NAEA\/UFPA<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Turma do Curso de Especializa\u00e7\u00e3o em Educa\u00e7\u00e3o Ambiental e Projeto Pedag\u00f3gico na Gest\u00e3o de Escolas e de Sistemas de Meio Ambiente na Amaz\u00f4nia \u2013 PPLS\/NAEA\/UFPA.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Parceria: NUMA\/UFPA.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h1 id=\"numa-lanca-programacao-especial-de-junho-em-alusao-ao-dia-mundial-do-meio-ambiente\" class=\"wp-block-heading\">NUMA lan\u00e7a programa\u00e7\u00e3o especial de junho em alus\u00e3o ao Dia Mundial do Meio Ambiente<\/h1>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/ufpa.br\/2026\/06\/03\/\"><time>03 de junho de 2026<\/time><\/a><\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/ufpa.br\/wp-content\/uploads\/2026\/06\/NUMA-.png\"><img decoding=\"async\" src=\"https:\/\/ufpa.br\/wp-content\/uploads\/2026\/06\/NUMA-.png\" alt=\"\" class=\"wp-image-82206\"\/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Em celebra\u00e7\u00e3o ao Dia Mundial do Meio Ambiente, comemorado no pr\u00f3ximo dia 5 de junho, o N\u00facleo de Meio Ambiente da UFPA (NUMA) preparou uma programa\u00e7\u00e3o especial que ocupar\u00e1 todo o m\u00eas com atividades abertas ao p\u00fablico sobre as quest\u00f5es socioambientais da Amaz\u00f4nia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As atividades t\u00eam in\u00edcio na sexta-feira, 5 de junho, \u00e0s 9h, com o lan\u00e7amento da Conflu\u00eancia, o evento de abertura que contar\u00e1 com a confer\u00eancia \u201cMeio Ambiente no s\u00e9culo XXI: o papel institucional do NUMA num cen\u00e1rio de conflitos e conflu\u00eancias\u201d, proferida pelo professor Christian Nunes, diretor do NUMA. A transmiss\u00e3o ser\u00e1 feita simultaneamente pelo&nbsp;<a href=\"https:\/\/www.youtube.com\/watch?v=gtjX2Qs3ldg\">canal do NUMA no YouTube<\/a>&nbsp;e pelo canal Amaz\u00f4nia em Quest\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ao longo das pr\u00f3ximas quatro semanas, o NUMA promover\u00e1 oficinas, minicursos, palestras, confer\u00eancias e rodas de conversa constru\u00eddas a partir do di\u00e1logo entre pesquisadores, estudantes, comunidades, movimentos sociais e institui\u00e7\u00f5es parceiras. Sem necessidade de inscri\u00e7\u00e3o pr\u00e9via.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A proposta \u00e9 criar um espa\u00e7o de troca de saberes plural e acess\u00edvel, conectando a universidade \u00e0 sociedade em torno dos desafios socioambientais que definem o presente e o futuro da regi\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A organiza\u00e7\u00e3o lembra que a agenda pode ser atualizada ao longo do m\u00eas, com inclus\u00e3o de novas atividades. A&nbsp;<a href=\"https:\/\/docs.google.com\/document\/d\/1OLJCLqD9_vdlU3cIWtkeYD08h6KbUmEG\/edit\">programa\u00e7\u00e3o completa<\/a>&nbsp;est\u00e1 dispon\u00edvel no&nbsp;<a href=\"https:\/\/www.numa.ufpa.br\/\">site da institui\u00e7\u00e3o<\/a>&nbsp;e nas redes sociais, onde tamb\u00e9m ser\u00e3o divulgadas novidades semanais.<\/p>\n\n\n\n<h2 id=\"leia-mais\" class=\"wp-block-heading\">Leia mais:<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">TEXTO:&nbsp;Com informa\u00e7\u00f5es Equipe NUMA\/UFPA<\/p>\n\n\n\n<h2 id=\"artes-divulgacao-numa-ufpa\" class=\"wp-block-heading\">ARTES:&nbsp;Divulga\u00e7\u00e3o NUMA\/UFPA<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Rela\u00e7\u00e3o com os ODS da ONU:<a href=\"https:\/\/ufpa.br\/numa-lanca-programacao-especial-de-junho-em-alusao-ao-dia-mundial-do-meio-ambiente\/?page_id=10007&amp;_sft_ods=ods-11\"><\/a><a href=\"https:\/\/ufpa.br\/numa-lanca-programacao-especial-de-junho-em-alusao-ao-dia-mundial-do-meio-ambiente\/?page_id=10007&amp;_sft_ods=ods-12\"><\/a><a href=\"https:\/\/ufpa.br\/numa-lanca-programacao-especial-de-junho-em-alusao-ao-dia-mundial-do-meio-ambiente\/?page_id=10007&amp;_sft_ods=ods-13\"><\/a><\/p>\n<div class=\"pvc_clear\"><\/div><p id=\"pvc_stats_3843\" class=\"pvc_stats all  \" data-element-id=\"3843\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" version=\"1.0\" viewBox=\"0 0 502 315\" preserveAspectRatio=\"xMidYMid meet\"><g transform=\"translate(0,332) scale(0.1,-0.1)\" fill=\"\" stroke=\"none\"><path d=\"M2394 3279 l-29 -30 -3 -207 c-2 -182 0 -211 15 -242 39 -76 157 -76 196 0 15 31 17 60 15 243 l-3 209 -33 29 c-26 23 -41 29 -80 29 -41 0 -53 -5 -78 -31z\"\/><path d=\"M3085 3251 c-45 -19 -58 -50 -96 -229 -47 -217 -49 -260 -13 -295 52 -53 146 -42 177 20 16 31 87 366 87 410 0 70 -86 122 -155 94z\"\/><path d=\"M1751 3234 c-13 -9 -29 -31 -37 -50 -12 -29 -10 -49 21 -204 19 -94 39 -189 45 -210 14 -50 54 -80 110 -80 34 0 48 6 76 34 21 21 34 44 34 59 0 14 -18 113 -40 219 -37 178 -43 195 -70 221 -36 32 -101 37 -139 11z\"\/><path d=\"M1163 3073 c-36 -7 -73 -59 -73 -102 0 -56 133 -378 171 -413 34 -32 83 -37 129 -13 70 36 67 87 -16 290 -86 209 -89 214 -129 231 -35 14 -42 15 -82 7z\"\/><path d=\"M3689 3066 c-15 -9 -33 -30 -42 -48 -48 -103 -147 -355 -147 -375 0 -98 131 -148 192 -74 13 15 57 108 97 206 80 196 84 226 37 273 -30 30 -99 39 -137 18z\"\/><path d=\"M583 2784 c-38 -19 -67 -74 -58 -113 9 -42 211 -354 242 -373 16 -10 45 -18 66 -18 51 0 107 52 107 100 0 39 -1 41 -124 234 -80 126 -108 162 -133 173 -41 17 -61 16 -100 -3z\"\/><path d=\"M4250 2784 c-14 -9 -74 -91 -133 -183 -95 -150 -107 -173 -107 -213 0 -55 33 -94 87 -104 67 -13 90 8 211 198 130 202 137 225 78 284 -27 27 -42 34 -72 34 -22 0 -50 -8 -64 -16z\"\/><path d=\"M2275 2693 c-553 -48 -1095 -270 -1585 -649 -135 -104 -459 -423 -483 -476 -23 -49 -22 -139 2 -186 73 -142 361 -457 571 -626 285 -228 642 -407 990 -497 242 -63 336 -73 660 -74 310 0 370 5 595 52 535 111 1045 392 1455 803 122 121 250 273 275 326 19 41 19 137 0 174 -41 79 -309 363 -465 492 -447 370 -946 591 -1479 653 -113 14 -422 18 -536 8z m395 -428 c171 -34 330 -124 456 -258 112 -119 167 -219 211 -378 27 -96 24 -300 -5 -401 -72 -255 -236 -447 -474 -557 -132 -62 -201 -76 -368 -76 -167 0 -236 14 -368 76 -213 98 -373 271 -451 485 -162 444 86 934 547 1084 153 49 292 57 452 25z m909 -232 c222 -123 408 -262 593 -441 76 -74 138 -139 138 -144 0 -16 -233 -242 -330 -319 -155 -123 -309 -223 -461 -299 l-81 -41 32 46 c18 26 49 83 70 128 143 306 141 649 -6 957 -25 52 -61 116 -79 142 l-34 47 45 -20 c26 -10 76 -36 113 -56z m-2057 25 c-40 -58 -105 -190 -130 -263 -110 -324 -59 -707 132 -981 25 -35 42 -64 37 -64 -19 0 -241 119 -326 174 -188 122 -406 314 -532 468 l-58 71 108 103 c185 178 428 349 672 473 66 33 121 60 123 61 2 0 -10 -19 -26 -42z\"\/><path d=\"M2375 1950 c-198 -44 -350 -190 -395 -379 -18 -76 -8 -221 19 -290 114 -284 457 -406 731 -260 98 52 188 154 231 260 27 69 37 214 19 290 -38 163 -166 304 -326 360 -67 23 -215 33 -279 19z\"\/><\/g><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/feminismo.org.br\/ULFA\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p><div class=\"pvc_clear\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Dia Nacional da Educa\u00e7\u00e3o Ambiental &#8211; Universidade Federal do Par\u00e1 &#8211; Brasil Abertura da Programa\u00e7\u00e3o de Junho Neste Dia Nacional da Educa\u00e7\u00e3o Ambiental, o GEAM\/NAEA\/UFPA e a Turma do Curso de Especializa\u00e7\u00e3o em Educa\u00e7\u00e3o Ambiental e Projeto Pedag\u00f3gico na Gest\u00e3o de Escolas e de Sistemas de Meio Ambiente na Amaz\u00f4nia (PPLS\/NAEA\/UFPA) d\u00e3o in\u00edcio \u00e0 programa\u00e7\u00e3o<\/p>\n","protected":false},"author":5419,"featured_media":3844,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_gspb_post_css":"","footnotes":""},"categories":[467,999,1000],"tags":[1001],"class_list":["post-3843","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil","category-meio-ambiente","category-ufpa","tag-meio-ambiente"],"acf":[],"a3_pvc":{"activated":true,"total_views":15,"today_views":0},"_links":{"self":[{"href":"https:\/\/feminismo.org.br\/ULFA\/wp-json\/wp\/v2\/posts\/3843","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/feminismo.org.br\/ULFA\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/feminismo.org.br\/ULFA\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/feminismo.org.br\/ULFA\/wp-json\/wp\/v2\/users\/5419"}],"replies":[{"embeddable":true,"href":"https:\/\/feminismo.org.br\/ULFA\/wp-json\/wp\/v2\/comments?post=3843"}],"version-history":[{"count":2,"href":"https:\/\/feminismo.org.br\/ULFA\/wp-json\/wp\/v2\/posts\/3843\/revisions"}],"predecessor-version":[{"id":3847,"href":"https:\/\/feminismo.org.br\/ULFA\/wp-json\/wp\/v2\/posts\/3843\/revisions\/3847"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/feminismo.org.br\/ULFA\/wp-json\/wp\/v2\/media\/3844"}],"wp:attachment":[{"href":"https:\/\/feminismo.org.br\/ULFA\/wp-json\/wp\/v2\/media?parent=3843"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/feminismo.org.br\/ULFA\/wp-json\/wp\/v2\/categories?post=3843"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/feminismo.org.br\/ULFA\/wp-json\/wp\/v2\/tags?post=3843"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}